{"id":44049,"date":"2015-09-23T07:07:55","date_gmt":"2015-09-23T07:07:55","guid":{"rendered":"http:\/\/punjabpost.in\/welcome\/?p=44049"},"modified":"2015-09-23T07:07:55","modified_gmt":"2015-09-23T07:07:55","slug":"%ef%bb%bf%e0%a8%a6%e0%a9%81%e0%a8%b2%e0%a8%ae%e0%a8%be%e0%a8%82-%e0%a8%95%e0%a8%b2%e0%a8%be%e0%a8%82-%e0%a8%b5%e0%a8%bf%e0%a8%96%e0%a9%87-%e0%a8%b2%e0%a9%8b%e0%a8%95%e0%a8%be%e0%a8%82-%e0%a8%a6","status":"publish","type":"post","link":"https:\/\/punjabpost.in\/welcome\/44049","title":{"rendered":"\ufeff\u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a05\u0a24\u0a47 \u0a2a\u0a48\u0a28\u0a36\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a3e\u0a30\u0a2e \u0a2d\u0a30\u0a47"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44050\" src=\"https:\/\/punjabpost.in\/welcome\/wp-content\/uploads\/2015\/09\/PPN2209201508.jpg\" alt=\"PPN2209201508\" width=\"1024\" height=\"481\" srcset=\"https:\/\/punjabpost.in\/welcome\/wp-content\/uploads\/2015\/09\/PPN2209201508.jpg 1024w, https:\/\/punjabpost.in\/welcome\/wp-content\/uploads\/2015\/09\/PPN2209201508-300x141.jpg 300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\u0a38\u0a70\u0a26\u0a4c\u0a5c, 22 \u0a38\u0a24\u0a70\u0a2c\u0a30 (\u0a39\u0a30\u0a2e\u0a3f\u0a70\u0a26\u0a30 \u0a38\u0a3f\u0a70\u0a18 \u0a2d\u0a71\u0a1f) &#8211; \u0a38\u0a30\u0a15\u0a3e\u0a30\u0a40 \u0a2a\u0a4d\u0a30\u0a3e\u0a07\u0a2e\u0a30\u0a40 \u0a38\u0a15\u0a42\u0a32 \u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a35\u0a71\u0a21\u0a40 \u0a17\u0a3f\u0a23\u0a24\u0a40 \u0a35\u0a3f\u0a1a \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a2c\u0a23\u0a3e\u0a0f \u0a17\u0a0f \u0a05\u0a24\u0a47 \u0a2a\u0a3f\u0a70\u0a21 \u0a26\u0a47 \u0a32\u0a4b\u0a5c\u0a2c\u0a70\u0a26 \u0a2a\u0a30\u0a3f\u0a35\u0a3e\u0a30\u0a3e\u0a02 \u0a26\u0a40\u0a06\u0a02 \u0a2a\u0a48\u0a28\u0a38\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a30\u0a3e\u0a2e \u0a35\u0a40 \u0a2d\u0a30\u0a47 \u0a17\u0a0f\u0964\u0a07\u0a38 \u0a38\u0a2c\u0a70\u0a27\u0a40 \u0a1c\u0a3e\u0a23\u0a15\u0a3e\u0a30\u0a40 \u0a26\u0a3f\u0a70\u0a26\u0a47 \u0a39\u0a4b\u0a0f \u0a05\u0a15\u0a3e\u0a32\u0a40 \u0a26\u0a32 \u0a26\u0a47 \u0a38\u0a70\u0a26\u0a4c\u0a5c \u0a38\u0a30\u0a15\u0a32 \u0a26\u0a47 \u0a10\u0a38.\u0a38\u0a40 \u0a35\u0a3f\u0a70\u0a17 \u0a26\u0a47 \u0a2a\u0a4d\u0a30\u0a27\u0a3e\u0a28 \u0a30\u0a3e\u0a1c \u0a38\u0a3f\u0a70\u0a18 \u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 (\u0a28\u0a70\u0a2c\u0a30\u0a26\u0a3e\u0a30) \u0a28\u0a47 \u0a26\u0a71\u0a38\u0a3f\u0a06 \u0a15\u0a3f \u0a38\u0a30\u0a15\u0a3e\u0a30 \u0a35\u0a71\u0a32\u0a4b\u0a02 \u0a35\u0a3f\u0a38\u0a47\u0a38 \u0a30\u0a42\u0a2a \u0a35\u0a3f\u0a1a \u0a2d\u0a3e\u0a35\u0a47\u0a02 \u0a15\u0a3f \u0a2a\u0a39\u0a3f\u0a32\u0a3e\u0a02 \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a2a\u0a3f\u0a70\u0a22 \u0a2a\u0a3f\u0a70\u0a21 \u0a1c\u0a3e \u0a15\u0a47 \u0a2c\u0a23\u0a3e\u0a0f \u0a17\u0a0f \u0a38\u0a28 \u0a2a\u0a30 \u0a35\u0a71\u0a21\u0a40 \u0a17\u0a3f\u0a23\u0a24\u0a40 \u0a35\u0a3f\u0a1a \u0a32\u0a4b\u0a15 \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a2c\u0a23\u0a3e\u0a09\u0a23 \u0a24\u0a4b\u0a02 \u0a35\u0a3e\u0a1d\u0a47 \u0a30\u0a39\u0a3f \u0a17\u0a0f \u0a38\u0a28 \u0a05\u0a24\u0a47 \u0a09\u0a28\u0a4d\u0a39\u0a3e\u0a02 \u0a26\u0a47 \u0a26\u0a41\u0a2c\u0a3e\u0a30\u0a3e \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a2c\u0a23\u0a3e\u0a09\u0a23 \u0a26\u0a47 \u0a32\u0a08 \u0a07\u0a39 \u0a15\u0a3e\u0a30\u0a1c \u0a15\u0a40\u0a24\u0a3e \u0a17\u0a3f\u0a06 \u0a39\u0a48\u0964\u0a09\u0a28\u0a4d\u0a39\u0a3e\u0a02 \u0a15\u0a3f\u0a39\u0a3e \u0a15\u0a3f \u0a2a\u0a70\u0a1c\u0a3e\u0a2c \u0a38\u0a30\u0a15\u0a3e\u0a30 \u0a35\u0a71\u0a32\u0a4b\u0a02 \u0a26\u0a3f\u0a71\u0a24\u0a40 \u0a1c\u0a3e\u0a02\u0a26\u0a40 \u0a2a\u0a48\u0a28\u0a38\u0a28 \u0a38\u0a15\u0a40\u0a2e \u0a35\u0a3f\u0a1a \u0a35\u0a71\u0a27 \u0a24\u0a4b\u0a02 \u0a35\u0a71\u0a27 \u0a32\u0a4b\u0a5c\u0a2c\u0a70\u0a26\u0a3e\u0a02 \u0a28\u0a42\u0a70 \u0a07\u0a38 \u0a38\u0a15\u0a40\u0a2e \u0a26\u0a3e \u0a32\u0a3e\u0a39\u0a3e \u0a26\u0a47\u0a23 \u0a32\u0a08 \u0a05\u0a71\u0a1c \u0a35\u0a71\u0a21\u0a40 \u0a17\u0a3f\u0a23\u0a24\u0a40 \u0a35\u0a3f\u0a1a \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a40\u0a06\u0a02 \u0a2a\u0a48\u0a28\u0a38\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a3e\u0a30\u0a2e \u0a35\u0a40 \u0a2d\u0a30\u0a47 \u0a17\u0a0f \u0a39\u0a28 \u0a24\u0a3e\u0a02 \u0a1c\u0a4b \u0a32\u0a4b\u0a15 \u0a28\u0a42\u0a70 \u0a38\u0a30\u0a15\u0a3e\u0a30 \u0a26\u0a40 \u0a07\u0a38 \u0a38\u0a39\u0a42\u0a32\u0a24 \u0a26\u0a3e \u0a32\u0a3e\u0a39\u0a3e \u0a2e\u0a3f\u0a32 \u0a38\u0a15\u0a47\u0964\u0a07\u0a38 \u0a2e\u0a4c\u0a15\u0a47 \u0a35\u0a48\u0a26 \u0a28\u0a30\u0a3f\u0a70\u0a26\u0a30 \u0a38\u0a3f\u0a70\u0a18 \u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02, \u0a28\u0a70\u0a2c\u0a30\u0a26\u0a3e\u0a30 \u0a17\u0a41\u0a32\u0a1c\u0a3e\u0a30 \u0a38\u0a3f\u0a70\u0a18 \u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02, \u0a2a\u0a4d\u0a30\u0a27\u0a3e\u0a28 \u0a17\u0a41\u0a30\u0a1a\u0a30\u0a28 \u0a38\u0a3f\u0a70\u0a18, \u0a2a\u0a4d\u0a30\u0a27\u0a3e\u0a28 \u0a1c\u0a38\u0a35\u0a70\u0a24 \u0a38\u0a3f\u0a70\u0a18 \u0a28\u0a70\u0a2c\u0a30\u0a26\u0a3e\u0a30 \u0a1c\u0a40\u0a24 \u0a38\u0a3f\u0a70\u0a18 \u0a06\u0a26\u0a3f \u0a39\u0a3e\u0a1c\u0a30 \u0a38\u0a28\u0964<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0a38\u0a70\u0a26\u0a4c\u0a5c, 22 \u0a38\u0a24\u0a70\u0a2c\u0a30 (\u0a39\u0a30\u0a2e\u0a3f\u0a70\u0a26\u0a30 \u0a38\u0a3f\u0a70\u0a18 \u0a2d\u0a71\u0a1f) &#8211; \u0a38\u0a30\u0a15\u0a3e\u0a30\u0a40 \u0a2a\u0a4d\u0a30\u0a3e\u0a07\u0a2e\u0a30\u0a40 \u0a38\u0a15\u0a42\u0a32 \u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a35\u0a71\u0a21\u0a40 \u0a17\u0a3f\u0a23\u0a24\u0a40 \u0a35\u0a3f\u0a1a \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a2c\u0a23\u0a3e\u0a0f \u0a17\u0a0f \u0a05\u0a24\u0a47 \u0a2a\u0a3f\u0a70\u0a21 \u0a26\u0a47 \u0a32\u0a4b\u0a5c\u0a2c\u0a70\u0a26 \u0a2a\u0a30\u0a3f\u0a35\u0a3e\u0a30\u0a3e\u0a02 \u0a26\u0a40\u0a06\u0a02 \u0a2a\u0a48\u0a28\u0a38\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a30\u0a3e\u0a2e \u0a35\u0a40 \u0a2d\u0a30\u0a47 \u0a17\u0a0f\u0964\u0a07\u0a38 \u0a38\u0a2c\u0a70\u0a27\u0a40 \u0a1c\u0a3e\u0a23\u0a15\u0a3e\u0a30\u0a40 \u0a26\u0a3f\u0a70\u0a26\u0a47 \u0a39\u0a4b\u0a0f \u0a05\u0a15\u0a3e\u0a32\u0a40 \u0a26\u0a32 \u0a26\u0a47 \u0a38\u0a70\u0a26\u0a4c\u0a5c \u0a38\u0a30\u0a15\u0a32 \u0a26\u0a47 \u0a10\u0a38.\u0a38\u0a40 \u0a35\u0a3f\u0a70\u0a17 \u0a26\u0a47 \u0a2a\u0a4d\u0a30\u0a27\u0a3e\u0a28 \u0a30\u0a3e\u0a1c \u0a38\u0a3f\u0a70\u0a18 \u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 (\u0a28\u0a70\u0a2c\u0a30\u0a26\u0a3e\u0a30) \u0a28\u0a47 \u0a26\u0a71\u0a38\u0a3f\u0a06 \u0a15\u0a3f &hellip;<\/p>\n","protected":false},"author":1,"featured_media":44050,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-44049","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-punjabnews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\ufeff\u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a05\u0a24\u0a47 \u0a2a\u0a48\u0a28\u0a36\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a3e\u0a30\u0a2e \u0a2d\u0a30\u0a47 | Punjab Post<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/punjabpost.in\/welcome\/44049\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ufeff\u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a05\u0a24\u0a47 \u0a2a\u0a48\u0a28\u0a36\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a3e\u0a30\u0a2e \u0a2d\u0a30\u0a47 | Punjab Post\" \/>\n<meta property=\"og:description\" content=\"\u0a38\u0a70\u0a26\u0a4c\u0a5c, 22 \u0a38\u0a24\u0a70\u0a2c\u0a30 (\u0a39\u0a30\u0a2e\u0a3f\u0a70\u0a26\u0a30 \u0a38\u0a3f\u0a70\u0a18 \u0a2d\u0a71\u0a1f) &#8211; \u0a38\u0a30\u0a15\u0a3e\u0a30\u0a40 \u0a2a\u0a4d\u0a30\u0a3e\u0a07\u0a2e\u0a30\u0a40 \u0a38\u0a15\u0a42\u0a32 \u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a35\u0a71\u0a21\u0a40 \u0a17\u0a3f\u0a23\u0a24\u0a40 \u0a35\u0a3f\u0a1a \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a2c\u0a23\u0a3e\u0a0f \u0a17\u0a0f \u0a05\u0a24\u0a47 \u0a2a\u0a3f\u0a70\u0a21 \u0a26\u0a47 \u0a32\u0a4b\u0a5c\u0a2c\u0a70\u0a26 \u0a2a\u0a30\u0a3f\u0a35\u0a3e\u0a30\u0a3e\u0a02 \u0a26\u0a40\u0a06\u0a02 \u0a2a\u0a48\u0a28\u0a38\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a30\u0a3e\u0a2e \u0a35\u0a40 \u0a2d\u0a30\u0a47 \u0a17\u0a0f\u0964\u0a07\u0a38 \u0a38\u0a2c\u0a70\u0a27\u0a40 \u0a1c\u0a3e\u0a23\u0a15\u0a3e\u0a30\u0a40 \u0a26\u0a3f\u0a70\u0a26\u0a47 \u0a39\u0a4b\u0a0f \u0a05\u0a15\u0a3e\u0a32\u0a40 \u0a26\u0a32 \u0a26\u0a47 \u0a38\u0a70\u0a26\u0a4c\u0a5c \u0a38\u0a30\u0a15\u0a32 \u0a26\u0a47 \u0a10\u0a38.\u0a38\u0a40 \u0a35\u0a3f\u0a70\u0a17 \u0a26\u0a47 \u0a2a\u0a4d\u0a30\u0a27\u0a3e\u0a28 \u0a30\u0a3e\u0a1c \u0a38\u0a3f\u0a70\u0a18 \u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 (\u0a28\u0a70\u0a2c\u0a30\u0a26\u0a3e\u0a30) \u0a28\u0a47 \u0a26\u0a71\u0a38\u0a3f\u0a06 \u0a15\u0a3f &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/punjabpost.in\/welcome\/44049\" \/>\n<meta property=\"og:site_name\" content=\"Punjab Post\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/punjabpost.in\/welcome\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-23T07:07:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/punjabpost.in\/welcome\/wp-content\/uploads\/2015\/09\/PPN2209201508.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"481\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ppadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ppadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/punjabpost.in\/welcome\/44049\",\"url\":\"https:\/\/punjabpost.in\/welcome\/44049\",\"name\":\"\ufeff\u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a05\u0a24\u0a47 \u0a2a\u0a48\u0a28\u0a36\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a3e\u0a30\u0a2e \u0a2d\u0a30\u0a47 | Punjab Post\",\"isPartOf\":{\"@id\":\"https:\/\/punjabpost.in\/welcome\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/punjabpost.in\/welcome\/44049#primaryimage\"},\"image\":{\"@id\":\"https:\/\/punjabpost.in\/welcome\/44049#primaryimage\"},\"thumbnailUrl\":\"https:\/\/punjabpost.in\/welcome\/wp-content\/uploads\/2015\/09\/PPN2209201508.jpg\",\"datePublished\":\"2015-09-23T07:07:55+00:00\",\"author\":{\"@id\":\"https:\/\/punjabpost.in\/welcome\/#\/schema\/person\/e389e50e8970b30f10352199927e8693\"},\"breadcrumb\":{\"@id\":\"https:\/\/punjabpost.in\/welcome\/44049#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/punjabpost.in\/welcome\/44049\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/punjabpost.in\/welcome\/44049#primaryimage\",\"url\":\"https:\/\/punjabpost.in\/welcome\/wp-content\/uploads\/2015\/09\/PPN2209201508.jpg\",\"contentUrl\":\"https:\/\/punjabpost.in\/welcome\/wp-content\/uploads\/2015\/09\/PPN2209201508.jpg\",\"width\":1024,\"height\":481},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/punjabpost.in\/welcome\/44049#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/punjabpost.in\/welcome\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ufeff\u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a05\u0a24\u0a47 \u0a2a\u0a48\u0a28\u0a36\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a3e\u0a30\u0a2e \u0a2d\u0a30\u0a47\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/punjabpost.in\/welcome\/#website\",\"url\":\"https:\/\/punjabpost.in\/welcome\/\",\"name\":\"Punjab Post\",\"description\":\"Daily Online Newspaper &amp; Print Media\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/punjabpost.in\/welcome\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/punjabpost.in\/welcome\/#\/schema\/person\/e389e50e8970b30f10352199927e8693\",\"name\":\"ppadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/punjabpost.in\/welcome\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7de9dc8774d44f6f6d7f7356a7a2363a4bd97c4f20720cdf463fc758fe348441?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7de9dc8774d44f6f6d7f7356a7a2363a4bd97c4f20720cdf463fc758fe348441?s=96&d=mm&r=g\",\"caption\":\"ppadmin\"},\"url\":\"https:\/\/punjabpost.in\/welcome\/author\/ppadmin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ufeff\u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a05\u0a24\u0a47 \u0a2a\u0a48\u0a28\u0a36\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a3e\u0a30\u0a2e \u0a2d\u0a30\u0a47 | Punjab Post","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/punjabpost.in\/welcome\/44049","og_locale":"en_US","og_type":"article","og_title":"\ufeff\u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a05\u0a24\u0a47 \u0a2a\u0a48\u0a28\u0a36\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a3e\u0a30\u0a2e \u0a2d\u0a30\u0a47 | Punjab Post","og_description":"\u0a38\u0a70\u0a26\u0a4c\u0a5c, 22 \u0a38\u0a24\u0a70\u0a2c\u0a30 (\u0a39\u0a30\u0a2e\u0a3f\u0a70\u0a26\u0a30 \u0a38\u0a3f\u0a70\u0a18 \u0a2d\u0a71\u0a1f) &#8211; \u0a38\u0a30\u0a15\u0a3e\u0a30\u0a40 \u0a2a\u0a4d\u0a30\u0a3e\u0a07\u0a2e\u0a30\u0a40 \u0a38\u0a15\u0a42\u0a32 \u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a35\u0a71\u0a21\u0a40 \u0a17\u0a3f\u0a23\u0a24\u0a40 \u0a35\u0a3f\u0a1a \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a2c\u0a23\u0a3e\u0a0f \u0a17\u0a0f \u0a05\u0a24\u0a47 \u0a2a\u0a3f\u0a70\u0a21 \u0a26\u0a47 \u0a32\u0a4b\u0a5c\u0a2c\u0a70\u0a26 \u0a2a\u0a30\u0a3f\u0a35\u0a3e\u0a30\u0a3e\u0a02 \u0a26\u0a40\u0a06\u0a02 \u0a2a\u0a48\u0a28\u0a38\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a30\u0a3e\u0a2e \u0a35\u0a40 \u0a2d\u0a30\u0a47 \u0a17\u0a0f\u0964\u0a07\u0a38 \u0a38\u0a2c\u0a70\u0a27\u0a40 \u0a1c\u0a3e\u0a23\u0a15\u0a3e\u0a30\u0a40 \u0a26\u0a3f\u0a70\u0a26\u0a47 \u0a39\u0a4b\u0a0f \u0a05\u0a15\u0a3e\u0a32\u0a40 \u0a26\u0a32 \u0a26\u0a47 \u0a38\u0a70\u0a26\u0a4c\u0a5c \u0a38\u0a30\u0a15\u0a32 \u0a26\u0a47 \u0a10\u0a38.\u0a38\u0a40 \u0a35\u0a3f\u0a70\u0a17 \u0a26\u0a47 \u0a2a\u0a4d\u0a30\u0a27\u0a3e\u0a28 \u0a30\u0a3e\u0a1c \u0a38\u0a3f\u0a70\u0a18 \u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 (\u0a28\u0a70\u0a2c\u0a30\u0a26\u0a3e\u0a30) \u0a28\u0a47 \u0a26\u0a71\u0a38\u0a3f\u0a06 \u0a15\u0a3f &hellip;","og_url":"https:\/\/punjabpost.in\/welcome\/44049","og_site_name":"Punjab Post","article_publisher":"https:\/\/www.facebook.com\/punjabpost.in\/welcome\/","article_published_time":"2015-09-23T07:07:55+00:00","og_image":[{"width":1024,"height":481,"url":"https:\/\/punjabpost.in\/welcome\/wp-content\/uploads\/2015\/09\/PPN2209201508.jpg","type":"image\/jpeg"}],"author":"ppadmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ppadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/punjabpost.in\/welcome\/44049","url":"https:\/\/punjabpost.in\/welcome\/44049","name":"\ufeff\u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a05\u0a24\u0a47 \u0a2a\u0a48\u0a28\u0a36\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a3e\u0a30\u0a2e \u0a2d\u0a30\u0a47 | Punjab Post","isPartOf":{"@id":"https:\/\/punjabpost.in\/welcome\/#website"},"primaryImageOfPage":{"@id":"https:\/\/punjabpost.in\/welcome\/44049#primaryimage"},"image":{"@id":"https:\/\/punjabpost.in\/welcome\/44049#primaryimage"},"thumbnailUrl":"https:\/\/punjabpost.in\/welcome\/wp-content\/uploads\/2015\/09\/PPN2209201508.jpg","datePublished":"2015-09-23T07:07:55+00:00","author":{"@id":"https:\/\/punjabpost.in\/welcome\/#\/schema\/person\/e389e50e8970b30f10352199927e8693"},"breadcrumb":{"@id":"https:\/\/punjabpost.in\/welcome\/44049#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/punjabpost.in\/welcome\/44049"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/punjabpost.in\/welcome\/44049#primaryimage","url":"https:\/\/punjabpost.in\/welcome\/wp-content\/uploads\/2015\/09\/PPN2209201508.jpg","contentUrl":"https:\/\/punjabpost.in\/welcome\/wp-content\/uploads\/2015\/09\/PPN2209201508.jpg","width":1024,"height":481},{"@type":"BreadcrumbList","@id":"https:\/\/punjabpost.in\/welcome\/44049#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/punjabpost.in\/welcome\/"},{"@type":"ListItem","position":2,"name":"\ufeff\u0a26\u0a41\u0a32\u0a2e\u0a3e\u0a02 \u0a15\u0a32\u0a3e\u0a02 \u0a35\u0a3f\u0a16\u0a47 \u0a32\u0a4b\u0a15\u0a3e\u0a02 \u0a26\u0a47 \u0a05\u0a27\u0a3e\u0a30 \u0a15\u0a3e\u0a30\u0a21 \u0a05\u0a24\u0a47 \u0a2a\u0a48\u0a28\u0a36\u0a28\u0a3e\u0a02 \u0a26\u0a47 \u0a2b\u0a3e\u0a30\u0a2e \u0a2d\u0a30\u0a47"}]},{"@type":"WebSite","@id":"https:\/\/punjabpost.in\/welcome\/#website","url":"https:\/\/punjabpost.in\/welcome\/","name":"Punjab Post","description":"Daily Online Newspaper &amp; Print Media","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/punjabpost.in\/welcome\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/punjabpost.in\/welcome\/#\/schema\/person\/e389e50e8970b30f10352199927e8693","name":"ppadmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/punjabpost.in\/welcome\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7de9dc8774d44f6f6d7f7356a7a2363a4bd97c4f20720cdf463fc758fe348441?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7de9dc8774d44f6f6d7f7356a7a2363a4bd97c4f20720cdf463fc758fe348441?s=96&d=mm&r=g","caption":"ppadmin"},"url":"https:\/\/punjabpost.in\/welcome\/author\/ppadmin"}]}},"_links":{"self":[{"href":"https:\/\/punjabpost.in\/welcome\/wp-json\/wp\/v2\/posts\/44049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/punjabpost.in\/welcome\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/punjabpost.in\/welcome\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/punjabpost.in\/welcome\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/punjabpost.in\/welcome\/wp-json\/wp\/v2\/comments?post=44049"}],"version-history":[{"count":1,"href":"https:\/\/punjabpost.in\/welcome\/wp-json\/wp\/v2\/posts\/44049\/revisions"}],"predecessor-version":[{"id":44051,"href":"https:\/\/punjabpost.in\/welcome\/wp-json\/wp\/v2\/posts\/44049\/revisions\/44051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/punjabpost.in\/welcome\/wp-json\/wp\/v2\/media\/44050"}],"wp:attachment":[{"href":"https:\/\/punjabpost.in\/welcome\/wp-json\/wp\/v2\/media?parent=44049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/punjabpost.in\/welcome\/wp-json\/wp\/v2\/categories?post=44049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/punjabpost.in\/welcome\/wp-json\/wp\/v2\/tags?post=44049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}